{"id":30,"date":"2023-11-27T09:10:55","date_gmt":"2023-11-27T09:10:55","guid":{"rendered":"https:\/\/demo.bravisthemes.com\/graviton\/?page_id=30"},"modified":"2026-07-01T23:31:31","modified_gmt":"2026-07-01T21:31:31","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.elmont-pro.com\/de\/contact\/","title":{"rendered":"Kontakt"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"30\" class=\"elementor elementor-30\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-793f8ad elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"793f8ad\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bf3e94b pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"bf3e94b\" data-element_type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-7571276 elementor-widget elementor-widget-pxl_image\" data-id=\"7571276\" data-element_type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-7571276-6780\" class=\"pxl-image-single pxl-disable-parallax-sm pxl-hide-sr-lg\" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                                <div class=\"pxl-item--bg bg-image\" style=\"background-image: url(https:\/\/www.elmont-pro.com\/wp-content\/uploads\/2024\/05\/el4.jpg);\"><\/div>\r\n                            \r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-be80f0e pxl-column-overflow-hidden-yes pxl-column-none\" data-id=\"be80f0e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fc51866 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"fc51866\" data-element_type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fba1417 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"fba1417\" data-element_type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-5267f8a elementor-widget elementor-widget-pxl_heading\" data-id=\"5267f8a\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-5267f8a-7358\" class=\"pxl-heading px-sub-title-dot-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\t<h3 class=\"pxl-item--title style-default highlight-default\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tKontakt\t\n\t\t\t\t\n\t\t<\/h3>\n\t<\/div>\n<\/div> \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7343dd elementor-widget__width-inherit elementor-widget elementor-widget-pxl_icon_box\" data-id=\"a7343dd\" data-element_type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-2 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>                                <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                        Adresse                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\">\u0160ale\u0161ka cesta 19A, 3320 Velenje, Slovenia<\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1728295 elementor-widget__width-inherit elementor-widget elementor-widget-pxl_icon_box\" data-id=\"1728295\" data-element_type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-2 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>                                <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                        Schreiben Sie uns                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\">info@elmont-pro.com<\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4c6028 elementor-widget__width-inherit elementor-widget elementor-widget-pxl_icon_box\" data-id=\"f4c6028\" data-element_type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box1 style-2 ani1\" data-wow-delay=\"ms\">\r\n    <div class=\"pxl-item--inner\">\r\n        \r\n                            <div class=\"pxl-item--icon\">\r\n                                    <i aria-hidden=\"true\" class=\"flaticon flaticon-phone\"><\/i>                                <\/div>\r\n                        <div class=\"pxl-item--meta\">\r\n            <h5 class=\"pxl-item--title el-empty\">\r\n                        Rufen Sie uns an                        <\/h5>\r\n            <div class=\"pxl-item--description el-empty\">+386 31 389 395\n<\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-99b9a8f pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"99b9a8f\" data-element_type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-71796c3 elementor-widget elementor-widget-pxl_contact_form\" data-id=\"71796c3\" data-element_type=\"widget\" data-widget_type=\"pxl_contact_form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-contact-form pxl-contact-form1 btn-w-auto\" data-wow-delay=\"ms\">\r\n        \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4810-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"4810\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/30#wpcf7-f4810-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/de\/wp-json\/wp\/v2\/pages\/30#wpcf7-f4810-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4810\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.2\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4810-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"uacf7-form-wrapper-container uacf7-form-4810\"><div class=\"wrap-ctf-popup wrap-form\">\n\t<div class=\"containter\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"input-filled col-xl-6 col-lg-6 col-md-6 col-sm-6 col-xs-12\">\n\t\t\t\t<span class=\"wpcf7-form-control-wrap your-name\">\n\t\t\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"*Ihr Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>   \n\t\t\t<div class=\"input-filled col-xl-6 col-lg-6 col-md-6 col-sm-6 col-xs-12\">\n\t\t\t\t<span class=\"wpcf7-form-control-wrap your-email\">\n\t\t\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"*Ihre E-Mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div> \t\t\n\t\t\t<div class=\"input-filled col-xl-12\">\n\t\t\t\t<span class=\"wpcf7-form-control-wrap your-phone\">\n\t\t\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"*Ihre Telefonnummer\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t<div class=\"input-filled col-xl-12\">\n\t\t\t\t<span class=\"wpcf7-form-control-wrap your-messeage\">\n\t\t\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nachricht schreiben....\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t<div class=\"input-filled col-xl-12 d-flex\"> \n                            \n\t\t\t\t<button type=\"submit\" class=\"wpcf7-submit wpcf7-btn-abs\" > Nachricht senden <i class=\"far fa-arrow-right\"><\/i> <\/button>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n<\/div>\n    <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-3cd4481 e-con-full e-flex e-con e-parent\" data-id=\"3cd4481\" data-element_type=\"container\">\t\t<div class=\"elementor-element elementor-element-8eb0f1d elementor-widget elementor-widget-google_maps\" data-id=\"8eb0f1d\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=%C5%A0alek%2090%2C%203320%20Velenje%2C%20Slovenia&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"\u0160alek 90, 3320 Velenje, Slowenien\"\n\t\t\t\t\taria-label=\"\u0160alek 90, 3320 Velenje, Slowenien\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Contact us Address \u0160ale\u0161ka cesta 19A, 3320 Velenje, Slovenia Write to us info@elmont-pro.com Call us +386 31 389 395 send message<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-30","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ElmontPro - Contact<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elmont-pro.com\/de\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ElmontPro - Contact\" \/>\n<meta property=\"og:description\" content=\"Contact us Address \u0160ale\u0161ka cesta 19A, 3320 Velenje, Slovenia Write to us info@elmont-pro.com Call us +386 31 389 395 send message\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elmont-pro.com\/de\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"ElmontPro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Elmont-PRO\/61579604308192\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T21:31:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elmont-pro.com\/wp-content\/uploads\/2024\/05\/elmont-pro-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"744\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elmont-pro.com\/contact\/\",\"url\":\"https:\/\/www.elmont-pro.com\/contact\/\",\"name\":\"ElmontPro - Contact\",\"isPartOf\":{\"@id\":\"https:\/\/www.elmont-pro.com\/#website\"},\"datePublished\":\"2023-11-27T09:10:55+00:00\",\"dateModified\":\"2026-07-01T21:31:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.elmont-pro.com\/contact\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elmont-pro.com\/contact\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elmont-pro.com\/contact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elmont-pro.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elmont-pro.com\/#website\",\"url\":\"https:\/\/www.elmont-pro.com\/\",\"name\":\"ElmontPro\",\"description\":\"Reliable electrical solutions for every project\",\"publisher\":{\"@id\":\"https:\/\/www.elmont-pro.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elmont-pro.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.elmont-pro.com\/#organization\",\"name\":\"ElmontPro\",\"url\":\"https:\/\/www.elmont-pro.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.elmont-pro.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.elmont-pro.com\/wp-content\/uploads\/2024\/05\/elmont-pro-logo.png\",\"contentUrl\":\"https:\/\/www.elmont-pro.com\/wp-content\/uploads\/2024\/05\/elmont-pro-logo.png\",\"width\":744,\"height\":514,\"caption\":\"ElmontPro\"},\"image\":{\"@id\":\"https:\/\/www.elmont-pro.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Elmont-PRO\/61579604308192\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ElmontPro - Contact","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elmont-pro.com\/de\/contact\/","og_locale":"de_DE","og_type":"article","og_title":"ElmontPro - Contact","og_description":"Contact us Address \u0160ale\u0161ka cesta 19A, 3320 Velenje, Slovenia Write to us info@elmont-pro.com Call us +386 31 389 395 send message","og_url":"https:\/\/www.elmont-pro.com\/de\/contact\/","og_site_name":"ElmontPro","article_publisher":"https:\/\/www.facebook.com\/people\/Elmont-PRO\/61579604308192\/","article_modified_time":"2026-07-01T21:31:31+00:00","og_image":[{"width":744,"height":514,"url":"https:\/\/www.elmont-pro.com\/wp-content\/uploads\/2024\/05\/elmont-pro-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elmont-pro.com\/contact\/","url":"https:\/\/www.elmont-pro.com\/contact\/","name":"ElmontPro - Contact","isPartOf":{"@id":"https:\/\/www.elmont-pro.com\/#website"},"datePublished":"2023-11-27T09:10:55+00:00","dateModified":"2026-07-01T21:31:31+00:00","breadcrumb":{"@id":"https:\/\/www.elmont-pro.com\/contact\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elmont-pro.com\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.elmont-pro.com\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elmont-pro.com\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.elmont-pro.com\/#website","url":"https:\/\/www.elmont-pro.com\/","name":"ElmontPro","description":"Reliable electrical solutions for every project","publisher":{"@id":"https:\/\/www.elmont-pro.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elmont-pro.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.elmont-pro.com\/#organization","name":"ElmontPro","url":"https:\/\/www.elmont-pro.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.elmont-pro.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.elmont-pro.com\/wp-content\/uploads\/2024\/05\/elmont-pro-logo.png","contentUrl":"https:\/\/www.elmont-pro.com\/wp-content\/uploads\/2024\/05\/elmont-pro-logo.png","width":744,"height":514,"caption":"ElmontPro"},"image":{"@id":"https:\/\/www.elmont-pro.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Elmont-PRO\/61579604308192\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.elmont-pro.com\/de\/wp-json\/wp\/v2\/pages\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elmont-pro.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.elmont-pro.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.elmont-pro.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elmont-pro.com\/de\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":76,"href":"https:\/\/www.elmont-pro.com\/de\/wp-json\/wp\/v2\/pages\/30\/revisions"}],"predecessor-version":[{"id":16788,"href":"https:\/\/www.elmont-pro.com\/de\/wp-json\/wp\/v2\/pages\/30\/revisions\/16788"}],"wp:attachment":[{"href":"https:\/\/www.elmont-pro.com\/de\/wp-json\/wp\/v2\/media?parent=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}